{"id":1137,"date":"2010-06-26T19:03:22","date_gmt":"2010-06-26T17:03:22","guid":{"rendered":"http:\/\/www.reha-psychologie.net\/reha\/?p=1137"},"modified":"2010-06-28T21:37:57","modified_gmt":"2010-06-28T19:37:57","slug":"wie-stark-sind-erwachsene-mit-adhs-und-komorbiden-stoerungen-in-ihrer-gesundheitsbezogenen-lebensqualitaet-beeintraechtigt","status":"publish","type":"post","link":"https:\/\/www.psychologie-aktuell.info\/reha\/2010\/06\/wie-stark-sind-erwachsene-mit-adhs-und-komorbiden-stoerungen-in-ihrer-gesundheitsbezogenen-lebensqualitaet-beeintraechtigt\/","title":{"rendered":"Wie stark sind Erwachsene mit ADHS und komorbiden St\u00f6rungen in ihrer gesundheitsbezogenen Lebensqualit\u00e4t beeintr\u00e4chtigt?"},"content":{"rendered":"<blockquote><p>Zur ADHS bei Erwachsenen liegen nur wenige Studien vor, die den Zusammenhang zwischen einer ADHS und komorbiden St\u00f6rung erheben und mit der gesundheitsbezogenen Lebensqualit\u00e4t in Verbindung bringen. Die Teilnehmer der Studie wurden per Kreuzklassifikation in Gruppen unterteilt, nachdem sie als auff\u00e4llig oder unauff\u00e4llig eingestuft wurden. Neben \u00cf\u20212-Tests und korrelativen Beziehungen wurden pr\u00e4diktive Werte und das relative Risiko bestimmt, um den Zusammenhang zwischen ADHS, komorbiden St\u00f6rungen und der gesundheitsbezogenen Lebensqualit\u00e4t zu ermitteln. <!--more-->W\u00e4hrend bei wenigen und begrenzten ADHS-Symptomen kaum komorbide St\u00f6rungen festzustellen waren, so treten in der H\u00e4lfte aller F\u00e4lle von ADHS weitere psychische Belastungsfaktoren auf. Dabei hatten ADHS-Betroffene ein deutlich h\u00f6heres Risiko f\u00fcr das Vorliegen psychischer Beschwerden als die Nichtbetroffenen. ADHS ist mit erh\u00f6hter psychischer Belastung bei gleichzeitiger Abnahme der gesundheitsbezogenen Lebensqualit\u00e4t verbunden. Neben dem generellen Nachweis einer hohen psychischen Belastung bei ADHS hat dies wichtige Konsequenzen f\u00fcr Diagnostik und Therapie. So ist eine umfassende Differenzialdiagnostik n\u00f6tig, damit eine Therapie auch komorbide St\u00f6rungen einbeziehen kann und sich somit die gesundheitsbezogene Lebensqualit\u00e4t verbessern l\u00e4sst.<\/p><\/blockquote>\n<p>Quelle: <a href=\"http:\/\/psycontent.metapress.com\/content\/4812knh2321415v4\/\">PsyCONTENT &#8211; Zeitschriftenbeitrag<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zur ADHS bei Erwachsenen liegen nur wenige Studien vor, die den Zusammenhang zwischen einer ADHS und komorbiden St\u00f6rung erheben und mit der gesundheitsbezogenen Lebensqualit\u00e4t in Verbindung bringen. Die Teilnehmer der Studie wurden per Kreuzklassifikation in Gruppen unterteilt, nachdem sie als &hellip; <a href=\"https:\/\/www.psychologie-aktuell.info\/reha\/2010\/06\/wie-stark-sind-erwachsene-mit-adhs-und-komorbiden-stoerungen-in-ihrer-gesundheitsbezogenen-lebensqualitaet-beeintraechtigt\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21,22],"tags":[142,52],"class_list":["post-1137","post","type-post","status-publish","format-standard","hentry","category-zeitschriftenartikel","category-allgemein","tag-adhs","tag-behandlung-therapie"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1fMVY-il","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/1137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/comments?post=1137"}],"version-history":[{"count":2,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/1137\/revisions"}],"predecessor-version":[{"id":2071,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/1137\/revisions\/2071"}],"wp:attachment":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/media?parent=1137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/categories?post=1137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/tags?post=1137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}