{"id":162,"date":"2008-08-01T22:47:18","date_gmt":"2008-08-01T20:47:18","guid":{"rendered":"http:\/\/www.reha-psychologie.net\/reha\/?p=162"},"modified":"2008-08-05T21:14:44","modified_gmt":"2008-08-05T19:14:44","slug":"info-broschure-der-barmer-zur-depression","status":"publish","type":"post","link":"https:\/\/www.psychologie-aktuell.info\/reha\/2008\/08\/info-broschure-der-barmer-zur-depression\/","title":{"rendered":"Info-Brosch\u00fcre der Barmer zur Depression"},"content":{"rendered":"<p>Mit Hilfe einer neuen Brosch\u00fcre der Barmer k\u00f6nnen Patienten und ihren Angeh\u00f6rigen sich die Auseinandersetzung mit dem Thema Depression erleichtern.<\/p>\n<p><!--more-->Unter dem Titel &#8222;Depressionen &#8211; Erkennen. Verstehen. Behandeln&#8220; finden Interessierte auf 32 Seiten Infos zu den verschiedenen Aspekten der Erkrankung wie den unterschiedlichen Formen der Depression, m\u00f6glichen Ursachen, Therapien und Hilfsangeboten.<\/p>\n<p>Die Brosch\u00fcre ist Teil einer Aufkl\u00e4rungskampagne der Barmer zur Depression.<\/p>\n<p><em>Die Brosch\u00fcre kann per Mail bestellt werden unter <a class=\"linkification-ext\" style=\"background-color: #fff9ab;\" title=\"Linkification: mailto:marianne.rudischer@barmer.de\" href=\"mailto:marianne.rudischer@barmer.de\">marianne.rudischer@barmer.de<\/a> , Tel. 018500992977.<\/em><\/p>\n<p>Quelle: <a href=\"http:\/\/www.aerztezeitung.de\/medizin\/krankheiten\/neuro-psychiatrische_krankheiten\/depressionen\/?sid=505035\" target=\"_blank\">Info-Brosch\u00fcre der Barmer zur Depression<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit Hilfe einer neuen Brosch\u00fcre der Barmer k\u00f6nnen Patienten und ihren Angeh\u00f6rigen sich die Auseinandersetzung mit dem Thema Depression erleichtern.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[65,32],"class_list":["post-162","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-broschuren","tag-depression"],"jetpack_shortlink":"https:\/\/wp.me\/p1fMVY-2C","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/comments?post=162"}],"version-history":[{"count":0,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/162\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/media?parent=162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/categories?post=162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/tags?post=162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}