{"id":2803,"date":"2010-11-30T22:02:11","date_gmt":"2010-11-30T21:02:11","guid":{"rendered":"http:\/\/www.psychologie-aktuell.info\/reha\/?p=2803"},"modified":"2010-12-01T17:55:12","modified_gmt":"2010-12-01T16:55:12","slug":"bindung-und-somatoforme-stoerungen-geringe-kohaerenz-und-unverarbeitete-bindungsrepraesentationen-bei-chronischem-schmerz","status":"publish","type":"post","link":"https:\/\/www.psychologie-aktuell.info\/reha\/2010\/11\/bindung-und-somatoforme-stoerungen-geringe-kohaerenz-und-unverarbeitete-bindungsrepraesentationen-bei-chronischem-schmerz\/","title":{"rendered":"Bindung und somatoforme St\u00f6rungen: Geringe Koh\u00e4renz und unverarbeitete Bindungsrepr\u00e4sentationen bei chronischem Schmerz"},"content":{"rendered":"<blockquote><p>Obwohl die Bindungstheorie ein einflussreicher Ansatz zur Erforschung psychischer St\u00f6rungen geworden ist, sind die Zusammenh\u00e4nge zwischen Bindung und somatoformen St\u00f6rungen bisher kaum untersucht. In dieser Studie wurden 15 Patienten mit einer somatoformen Schmerzst\u00f6rung mit 15 klinisch unauff\u00e4lligen Kontrollprobanden verglichen. <!--more-->Die Bindungsrepr\u00e4sentationen wurden mit dem Adult Attachment Interview (AAI) erfasst. Im Vergleich zur Kontrollgruppe beschreiben die Patienten das Verhalten ihrer Eltern als weniger liebevoll und als zur\u00fcckweisender, bringen mehr \u00c4rger auf die Mutter zum Ausdruck, zeigen mehr Anzeichen unverarbeiteter Verluste und Traumata, und ihre Interviews sind deutlich weniger koh\u00e4rent. Kein Patient wird als sicher klassifiziert; die Mehrheit entf\u00e4llt auf die Kategorie der unverarbeiteten Bindung. Die Befunde dieser Studie k\u00f6nnen zum besseren Verst\u00e4ndnis der h\u00e4ufig beschriebenen Probleme in der therapeutischen Beziehung mit diesen Patienten beitragen.<\/p><\/blockquote>\n<p>Quelle: <a href=\"https:\/\/www.thieme-connect.de\/DOI\/DOI?10.1055\/s-0030-1265160\">Thieme eJournals &#8211; Abstract<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obwohl die Bindungstheorie ein einflussreicher Ansatz zur Erforschung psychischer St\u00f6rungen geworden ist, sind die Zusammenh\u00e4nge zwischen Bindung und somatoformen St\u00f6rungen bisher kaum untersucht. In dieser Studie wurden 15 Patienten mit einer somatoformen Schmerzst\u00f6rung mit 15 klinisch unauff\u00e4lligen Kontrollprobanden verglichen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[338,104],"class_list":["post-2803","post","type-post","status-publish","format-standard","hentry","category-zeitschriftenartikel","tag-schmerz","tag-trauma"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1fMVY-Jd","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/2803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/comments?post=2803"}],"version-history":[{"count":1,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/2803\/revisions"}],"predecessor-version":[{"id":2882,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/2803\/revisions\/2882"}],"wp:attachment":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/media?parent=2803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/categories?post=2803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/tags?post=2803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}