{"id":3469,"date":"2011-03-01T08:26:13","date_gmt":"2011-03-01T07:26:13","guid":{"rendered":"http:\/\/www.psychologie-aktuell.info\/reha\/?p=3469"},"modified":"2011-02-26T22:17:28","modified_gmt":"2011-02-26T21:17:28","slug":"psychosoziale-arbeitsbelastungen-und-depressive-symptome-bei-fuhrungskraften","status":"publish","type":"post","link":"https:\/\/www.psychologie-aktuell.info\/reha\/2011\/03\/psychosoziale-arbeitsbelastungen-und-depressive-symptome-bei-fuhrungskraften\/","title":{"rendered":"Psychosoziale Arbeitsbelastungen und depressive Symptome bei F\u00fchrungskr\u00e4ften"},"content":{"rendered":"<blockquote><p><strong>Iris-Andrea Kuhnke-Wagner, Jan Heidenreich and Gernot Brauchle<\/strong><\/p>\n<p>Die vorgestellte Studie untersucht den Zusammenhang zwischen dem Ausma\u00df erfahrener Arbeitsbelastungen und depressiven Symptomen bei F\u00fchrungskr\u00e4ften.<br \/>\nIn einer Querschnittstudie wurden 154 F\u00fchrungskr\u00e4fte mithilfe des Fragebogens zum Modell beruflicher Gratifikationskrisen und der allgemeinen Depressionsskala (ADS) befragt. <!--more-->Dabei erfolgte zus\u00e4tzlich zum Gesamtquotienten von Verausgabung und Belohnung eine separate Betrachtung der 3 Belohnungsdimensionen.<br \/>\nDie logistischen Regressionsanalysen zeigen nach Ber\u00fccksichtigung der Kontrollvariablen signifikant erh\u00f6hte Risiken [\u201codds ratio\u201c (OR) 4,4] f\u00fcr depressive Symptome bei F\u00fchrungskr\u00e4ften, die durch ein Ungleichgewicht von Verausgabung und Belohnung belastet sind.<br \/>\nDie Untersuchungsergebnisse deuten darauf hin, dass die 3 Belohnungsdimensionen unterschiedlich relevant sind. Pr\u00e4ventiv sind insbesondere bei einer Reduzierung des Ungleichgewichts von Verausgabung und Wertsch\u00e4tzung\/Anerkennung der geleisteten Arbeit geringere gesundheitliche Einschr\u00e4nkungen durch depressive Symptome zu erwarten.<\/p><\/blockquote>\n<p>Quelle: <a href=\"http:\/\/www.springerlink.com\/content\/0935-6185\/56\/1\/\">SpringerLink &#8211; Psychotherapeut, Volume 56, Number 1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iris-Andrea Kuhnke-Wagner, Jan Heidenreich and Gernot Brauchle Die vorgestellte Studie untersucht den Zusammenhang zwischen dem Ausma\u00df erfahrener Arbeitsbelastungen und depressiven Symptomen bei F\u00fchrungskr\u00e4ften. In einer Querschnittstudie wurden 154 F\u00fchrungskr\u00e4fte mithilfe des Fragebogens zum Modell beruflicher Gratifikationskrisen und der allgemeinen Depressionsskala &hellip; <a href=\"https:\/\/www.psychologie-aktuell.info\/reha\/2011\/03\/psychosoziale-arbeitsbelastungen-und-depressive-symptome-bei-fuhrungskraften\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[228,32,732,733],"class_list":["post-3469","post","type-post","status-publish","format-standard","hentry","category-zeitschriftenartikel","tag-belastung","tag-depression","tag-fuhrungskrafte","tag-gratifikationskrise"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1fMVY-TX","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/3469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/comments?post=3469"}],"version-history":[{"count":2,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/3469\/revisions"}],"predecessor-version":[{"id":3480,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/3469\/revisions\/3480"}],"wp:attachment":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/media?parent=3469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/categories?post=3469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/tags?post=3469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}