{"id":3659,"date":"2011-05-03T11:38:36","date_gmt":"2011-05-03T09:38:36","guid":{"rendered":"http:\/\/www.psychologie-aktuell.info\/reha\/?p=3659"},"modified":"2011-04-29T08:59:51","modified_gmt":"2011-04-29T06:59:51","slug":"psychoedukation-bei-depressiven-storungen-erfassung-von-interventionsmerkmalen-und-behandlungskompetenzen","status":"publish","type":"post","link":"https:\/\/www.psychologie-aktuell.info\/reha\/2011\/05\/psychoedukation-bei-depressiven-storungen-erfassung-von-interventionsmerkmalen-und-behandlungskompetenzen\/","title":{"rendered":"Psychoedukation bei depressiven St\u00f6rungen &#8211; Erfassung von Interventionsmerkmalen und Behandlungskompetenzen"},"content":{"rendered":"<blockquote><p><strong>Florian Weck, Martin Hautzinger, Thomas Heidenreich, Ulrich Stangier<\/strong><br \/>\nPsychoedukation ist eine effektive Behandlungsmethode f\u00fcr depressive St\u00f6rungen. In der vorliegenden Arbeit werden Merkmale und Kompetenzen der psychoedukativen Behandlung (SK-P) entwickelt, gemessen und validiert. Grundlage bildeten <!--more-->30 Sitzungsvideos einer Psychoedukation zur Behandlung rezidivierender Depressionen. Die Behandler wurden hinsichtlich ihrer Kompetenz bei der Durchf\u00fchrung der Psychoedukation von 2 unabh\u00e4ngigen Beurteilern eingesch\u00e4tzt. Faktorenanalytisch lie\u00df sich eine Einfaktorenstruktur extrahieren. Die aus 8 Items bestehende Skala wies eine hohe interne Konsistenz (\u03b1=0,92) und Beurteiler\u00fcbereinstimmung (ICC=0,87) auf. Zudem zeigte sich ein Zusammenhang zwischen der Kompetenz der Behandler und der durch die Patienten wahrgenommenen Qualit\u00e4t der therapeutischen Beziehung (r=0,46). Die SK-P stellt somit ein vielversprechendes Instrument zur \u00dcberpr\u00fcfung der Kompetenzen von Behandlern bei der Durchf\u00fchrung von Psychoedukation bei Depressionen dar.<\/p><\/blockquote>\n<p>Quelle: <a href=\"https:\/\/www.thieme-connect.de\/DOI\/DOI?10.1055\/s-0030-1269902\">Thieme eJournals &#8211; Abstract<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Florian Weck, Martin Hautzinger, Thomas Heidenreich, Ulrich Stangier Psychoedukation ist eine effektive Behandlungsmethode f\u00fcr depressive St\u00f6rungen. In der vorliegenden Arbeit werden Merkmale und Kompetenzen der psychoedukativen Behandlung (SK-P) entwickelt, gemessen und validiert. Grundlage bildeten<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[32,746,770],"class_list":["post-3659","post","type-post","status-publish","format-standard","hentry","category-zeitschriftenartikel","tag-depression","tag-psychoedukation","tag-sk-p"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1fMVY-X1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/3659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/comments?post=3659"}],"version-history":[{"count":1,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/3659\/revisions"}],"predecessor-version":[{"id":3718,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/3659\/revisions\/3718"}],"wp:attachment":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/media?parent=3659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/categories?post=3659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/tags?post=3659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}