{"id":3665,"date":"2011-05-08T08:05:10","date_gmt":"2011-05-08T06:05:10","guid":{"rendered":"http:\/\/www.psychologie-aktuell.info\/reha\/?p=3665"},"modified":"2011-05-04T08:43:21","modified_gmt":"2011-05-04T06:43:21","slug":"psychopharmakotherapie-des-depressiven-herzpatienten","status":"publish","type":"post","link":"https:\/\/www.psychologie-aktuell.info\/reha\/2011\/05\/psychopharmakotherapie-des-depressiven-herzpatienten\/","title":{"rendered":"Psychopharmakotherapie des depressiven Herzpatienten"},"content":{"rendered":"<blockquote><p><strong>Florian  Lederbogen<\/strong><br \/>\nDie Psychopharmakotherapie stellt eine wichtige Therapieoption bei der Behandlung des depressiven Herzpatienten dar. Koordiniert mit anderen therapeutischen Ma\u00dfnahmen, ist sie bei mittelschweren und schweren depressiven Episoden indiziert und sollte unter Ber\u00fccksichtigung der geltenden Therapieleitlinien durchgef\u00fchrt werden. Substanzen erster Wahl sind Wirkstoffe aus der Gruppe der selektiven Serotonin-R\u00fcckaufnahmeinhibitoren (SSRI), insbesondere die Substanzen Sertralin und Citalopram. Diese Substanzen zeichnen sich durch eine hohe <!--more-->therapeutische Sicherheit beim depressiven Herzpatienten aus. Eine gegen\u00fcber der Gabe von Placebo nachgewiesene Wirksamkeit wurde gefunden bei depressiven Patienten mit chronischer koronarer Herzkrankheit, nicht jedoch bei Patienten mit einer Herzinsuffizienz. Nach einem akuten isch\u00e4mischen Ereignis (Myokardinfarkt, instabile Angina pectoris) profitieren nach den bislang vorliegenden Daten nur diejenigen Patienten von einer antidepressiven Pharmakotherapie, die an einer schweren oder rezidivierenden depressiven St\u00f6rung leiden, au\u00dferdem solchen, bei denen die Depression bereits vor dem kardialen Ereignis begonnen hatte. Erste Ergebnisse deuten darauf hin, dass sich durch eine erfolgreiche antidepressive Pharmakotherapie die im Vergleich zu nicht depressiven Herzpatienten ung\u00fcnstigere kardiale Prognose verbessern l\u00e4sst.<\/p><\/blockquote>\n<p>Quelle: <a href=\"https:\/\/www.thieme-connect.de\/DOI\/DOI?10.1055\/s-0030-1266032\">Thieme eJournals &#8211; Abstract<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Florian Lederbogen Die Psychopharmakotherapie stellt eine wichtige Therapieoption bei der Behandlung des depressiven Herzpatienten dar. Koordiniert mit anderen therapeutischen Ma\u00dfnahmen, ist sie bei mittelschweren und schweren depressiven Episoden indiziert und sollte unter Ber\u00fccksichtigung der geltenden Therapieleitlinien durchgef\u00fchrt werden. Substanzen erster &hellip; <a href=\"https:\/\/www.psychologie-aktuell.info\/reha\/2011\/05\/psychopharmakotherapie-des-depressiven-herzpatienten\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[32,773,772,321,771,212],"class_list":["post-3665","post","type-post","status-publish","format-standard","hentry","category-zeitschriftenartikel","tag-depression","tag-herzinsuffizienz","tag-khk","tag-leitlinie","tag-psychopharmakotherapie","tag-wirksamkeit"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1fMVY-X7","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/3665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/comments?post=3665"}],"version-history":[{"count":2,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/3665\/revisions"}],"predecessor-version":[{"id":3731,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/posts\/3665\/revisions\/3731"}],"wp:attachment":[{"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/media?parent=3665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/categories?post=3665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psychologie-aktuell.info\/reha\/wp-json\/wp\/v2\/tags?post=3665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}